{"id":103183,"date":"2026-01-23T10:12:54","date_gmt":"2026-01-23T10:12:54","guid":{"rendered":"https:\/\/tuavaluo.com\/avaluo\/2026\/01\/23\/el-bitcoin-y-las-criptos-vuelven-a-tenirse-de-rojo-por-la-persistente-incertidumbre-geopolitica\/"},"modified":"2026-01-23T10:12:54","modified_gmt":"2026-01-23T10:12:54","slug":"el-bitcoin-y-las-criptos-vuelven-a-tenirse-de-rojo-por-la-persistente-incertidumbre-geopolitica","status":"publish","type":"post","link":"https:\/\/tuavaluo.com\/avaluo\/2026\/01\/23\/el-bitcoin-y-las-criptos-vuelven-a-tenirse-de-rojo-por-la-persistente-incertidumbre-geopolitica\/","title":{"rendered":"El bitcoin y las criptos vuelven a te\u00f1irse de rojo por la persistente incertidumbre geopol\u00edtica"},"content":{"rendered":"<p>Las &#8216;altcoins&#8217; no lo hacen mejor. XRP, <strong>Binance coin (BNB), solana (SOL), cardano (ADA), dogecoin (DOGE) o chainlink (LINK)<\/strong>, entre otros tokens, caen algo m\u00e1s de un 2% de media. En el lado positivo destacan las alzas de m\u00e1s del 2% en <strong>tron (TRX)<\/strong> y de algo m\u00e1s del 1% en <strong>monero<\/strong> <strong>(XMR)<\/strong>, que, no obstante, ha perdido m\u00e1s de un 25% de su valor en los \u00faltimos siete d\u00edas.<\/p>\n<p>En cuanto a los <strong>fondos cotizados<\/strong> (ETF, por sus siglas en ingl\u00e9s) al contado, los de bitcoin cerraron la jornada con salidas netas de 32,2 millones de d\u00f3lares y los de ETH, con salidas netas de 42 millones de d\u00f3lares. Cabe se\u00f1alar que apenas hubo movimientos en la mayor\u00eda de los fondos, ya que las pocas salidas se concentraron en unos pocos productos cotizados, como el IBIT o el ETHA, ambos gestionados por BlackRock.<\/p>\n<p>Numerosos expertos advierten que <a href=\"https:\/\/www.bolsamania.com\/noticias\/mercados\/analistas-valoran-preacuerdo-trump-groenlandia-volatilidad-seguira-latente--21535815.html\" target=\"_blank\"  rel=\"nofollow\" ><strong>la incertidumbre sigue siendo la norma en el mercado<\/strong><\/a>, ya que la incertidumbre geopol\u00edtica no se ha reducido pese al <strong>preacuerdo alcanzado entre EEUU y la OTAN sobre Groenlandia<\/strong>. El presidente de EEUU, Donald Trump, <a href=\"https:\/\/www.bolsamania.com\/noticias\/economia\/pacto-trump-otan-implicaria-presencia-minas-misiles-eeuu-groenlandia--21539249.html\" target=\"_blank\"  rel=\"nofollow\" ><strong>apenas ha dado detalles sobre el mismo<\/strong><\/a> y Dinamarca insisti\u00f3 en que su soberan\u00eda sobre la isla no estaba sujeta a discusi\u00f3n. Adem\u00e1s, los analistas advierten que la volatilidad seguir\u00e1 siendo la t\u00f3nica habitual en el mercado por la imprevisibilidad de las pol\u00edticas del presidente estadounidense.<\/p>\n<p>Esta aversi\u00f3n al riesgo es lo que est\u00e1 lastrando a las criptomonedas y beneficiando a activos considerados m\u00e1s seguros, como <a href=\"https:\/\/www.bolsamania.com\/noticias\/mercados\/oro-marca-otro-record-historico-conquistar-4900-dolares-5000--21542307.html\" target=\"_blank\"  rel=\"nofollow\" ><strong>el oro, que se acerca a los 5.000 d\u00f3lares<\/strong><\/a>. Ello, a pesar de que la <strong>debilidad del d\u00f3lar<\/strong> ha sido hist\u00f3ricamente positiva para el bitcoin, pero, en estos momentos, la criptomoneda reina sigue negoci\u00e1ndose como un activo de riesgo.<\/p>\n<p>\u00abLas criptomonedas a\u00fan se negocian como <a href=\"https:\/\/www.bolsamania.com\/noticias\/criptodivisas\/criptomonedas-respiran-aliviadas-suben-preacuerdo-groenlandia--21536019.html\" target=\"_blank\"  rel=\"nofollow\" ><strong>un amplificador de volatilidad en lugar de un activo defensivo<\/strong><\/a>. La venta por liquidaci\u00f3n elimin\u00f3 el exceso de apalancamiento, pero la incertidumbre sobre pol\u00edticas, costos de financiamiento y regulaci\u00f3n mantiene a los inversores selectivos en lugar de agresivos\u00bb, explica Wenny Cai, directora de operaciones de Synfutures, en declaraciones concedidas a &#8216;CoinDesk&#8217;.<\/p>\n<p>Por otro lado, la decisi\u00f3n del Banco de Jap\u00f3n (BOJ) tampoco parece que pueda favorecer al bitcoin a corto plazo. El organismo <a href=\"https:\/\/www.bolsamania.com\/noticias\/economia\/banco-de-japon-mantiene-tipos-mejora-previsiones-elecciones-anticipadas--21541898.html\" target=\"_blank\"  rel=\"nofollow\" ><strong>decidi\u00f3 mantener su tasa de referencia en el 0,75%<\/strong><\/a>, al tiempo que aument\u00f3 sus pron\u00f3sticos de crecimiento e inflaci\u00f3n para los ejercicios fiscales 2025 y 2026, citando apoyo a la pol\u00edtica fiscal expansiva de la primera ministra Sanae Takaichi. Seg\u00fan algunos estrategas, es probable que el yen permanezca d\u00e9bil en el corto plazo, un pron\u00f3stico que podr\u00eda ser bajista para BTC dado la fuerte correlaci\u00f3n positiva reciente entre ambos activos.<\/p>\n<p>Por otro lado, <a href=\"https:\/\/www.bolsamania.com\/noticias\/mercados\/rentabilidad-bonos-japoneses-test-credibilidad-japon--21521154.html\" target=\"_blank\"  rel=\"nofollow\" ><strong>las rentabilidades de los bonos japoneses volvieron a subir<\/strong><\/a>, lo que podr\u00eda seguir presionando al bitcoin. Cuando los rendimientos japoneses a largo plazo se disparan, aumenta el costo de endeudamiento global y fomenta que los inversores retiren dinero hacia activos m\u00e1s seguros y que generen intereses. Ese cambio normalmente perjudica a los mercados especulativos como las criptomonedas, que dependen de condiciones financieras relajadas y de abundante liquidez.<\/p>\n<p>Y lo peor podr\u00eda estar por venir. Seg\u00fan los analistas de Glassnode, varios indicadores &#8216;on-chain&#8217;, como el coste base de los compradores a corto plazo, parece <a href=\"https:\/\/www.bolsamania.com\/noticias\/criptodivisas\/goldman-sachs-buen-momento-vender-bitcoin-antes-invierno--21511676.html\" target=\"_blank\"  rel=\"nofollow\" ><strong>adelantar nuevas ca\u00eddas para la criptomoneda reina<\/strong><\/a>. En concreto, sugieren que gran parte de la presi\u00f3n vendedora proviene de inversores que acumularon BTC entre principios y mediados de 2025 y que ahora est\u00e1n saliendo de sus posiciones a medida que el precio revisita su rango de entrada.<\/p>\n<p>\u00abEl exceso de oferta persiste, ya que los compradores recientes siguen enfrentando resistencia superior, limitando el seguimiento alcista y dejando las subidas vulnerables a la distribuci\u00f3n\u00bb, se\u00f1alan. Adem\u00e1s, estos analistas afirman que la acumulaci\u00f3n sigue siendo selectiva en lugar de agresiva, sin alcanzar la demanda sostenida que normalmente se asocia con un rally alcista sostenido.<\/p>\n<p>Source: Bolsamania.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las &#8216;altcoins&#8217; no lo hacen mejor. XRP, Binance coin (BNB), solana (SOL), cardano (ADA), dogecoin (DOGE) o chainlink (LINK), entre&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[104],"tags":[99],"_links":{"self":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/103183"}],"collection":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/comments?post=103183"}],"version-history":[{"count":0,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/103183\/revisions"}],"wp:attachment":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/media?parent=103183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/categories?post=103183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/tags?post=103183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}