{"id":28318,"date":"2020-12-10T11:24:50","date_gmt":"2020-12-10T11:24:50","guid":{"rendered":"https:\/\/tuavaluo.com\/avaluo\/2020\/12\/10\/el-ine-eleva-a-45-684-los-muertos-por-covid-en-espana-hasta-mayo\/"},"modified":"2020-12-10T11:24:50","modified_gmt":"2020-12-10T11:24:50","slug":"el-ine-eleva-a-45-684-los-muertos-por-covid-en-espana-hasta-mayo","status":"publish","type":"post","link":"https:\/\/tuavaluo.com\/avaluo\/2020\/12\/10\/el-ine-eleva-a-45-684-los-muertos-por-covid-en-espana-hasta-mayo\/","title":{"rendered":"El INE eleva a 45.684 los muertos por Covid en Espa\u00f1a hasta mayo"},"content":{"rendered":"<div class=\"read-more-links\">\n<h5>Noticia relacionada<\/h5>\n<p><a class=\"readMore\" href=\"https:\/\/www.bolsamania.com\/noticias\/sanidad\/sanidad-notifica-17681-casos-394-muertes-covid--7739544.html\" rel=\"noopener noreferrer\" target=\"_blank\" data-id=\"7739544\" rel=\"nofollow\" ><\/p>\n<figure><img class=\"lazy\" title=\"Leer m&#xE1;s\" data-original=\"https:\/\/img3.s3wfg.com\/web\/img\/images_uploaded\/f\/1\/coronavirus-covid-contaminations-hopital-marseille_20201016133533.jpg\" data-src=\"https:\/\/img3.s3wfg.com\/web\/img\/images_uploaded\/f\/1\/coronavirus-covid-contaminations-hopital-marseille_20201016133533.jpg\" \/><\/figure>\n<p>Sanidad notifica 17.681 casos y 394 muertes por Covid desde el viernes <\/a><\/div>\n<p>\u00abLa COVID-19, del grupo de enfermedades infecciosas, fue la causa de muerte m\u00e1s frecuente en los cinco primeros meses de 2020. En el caso de <strong>COVID-19 virus identificado<\/strong>, fallecieron <strong>32.652 personas<\/strong> (con una tasa de 68,8 por cada 100.000 habitantes); y en el de <strong>COVID-19 sospechoso<\/strong> murieron <strong>13.032 personas<\/strong> (con una tasa de 27,5)\u00bb, ha explicado el INE en nota de prensa.<\/p>\n<p>Durante el periodo enero-mayo de 2020, se produjeron en Espa\u00f1a<strong> 231.014 defunciones<\/strong>, 43.537 m\u00e1s que en el mismo periodo del a\u00f1o anterior (un 23,2% m\u00e1s). Por sexo, fallecieron 115.541 hombres (un 21,9% m\u00e1s) y 115.473 mujeres (un 24,6% m\u00e1s).<\/p>\n<p>Aunque la variaci\u00f3n del n\u00famero de fallecimientos en este periodo \u00abpresent\u00f3 distinta tendencia en los meses de enero y febrero y en los de marzo a mayo\u00bb, a\u00f1ade el INE.<\/p>\n<p>As\u00ed, <strong>el n\u00famero de defunciones descendi\u00f3 un 4,3% durante enero y febrero<\/strong> respecto al mismo periodo de 2019 (con 3.568 menos). Pero en el periodo de marzo a mayo de 2020, cuando comez\u00f3 la pandemia, <strong>el n\u00famero de fallecimientos se increment\u00f3 un 44,8% (con 47.105 m\u00e1s)<\/strong>.<\/p>\n<p>&#013;<br \/>\nSource: Bolsamania.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noticia relacionada Sanidad notifica 17.681 casos y 394 muertes por Covid desde el viernes \u00abLa COVID-19, del grupo de enfermedades&#8230;<\/p>\n","protected":false},"author":3,"featured_media":28319,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[104],"tags":[99],"_links":{"self":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/28318"}],"collection":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/comments?post=28318"}],"version-history":[{"count":0,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/28318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/media\/28319"}],"wp:attachment":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/media?parent=28318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/categories?post=28318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/tags?post=28318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}