{"id":51327,"date":"2022-03-03T16:03:33","date_gmt":"2022-03-03T16:03:33","guid":{"rendered":"https:\/\/tuavaluo.com\/avaluo\/2022\/03\/03\/el-decalogo-de-la-aie-para-que-europa-reduzca-su-dependencia-del-gas-ruso\/"},"modified":"2022-03-03T16:03:33","modified_gmt":"2022-03-03T16:03:33","slug":"el-decalogo-de-la-aie-para-que-europa-reduzca-su-dependencia-del-gas-ruso","status":"publish","type":"post","link":"https:\/\/tuavaluo.com\/avaluo\/2022\/03\/03\/el-decalogo-de-la-aie-para-que-europa-reduzca-su-dependencia-del-gas-ruso\/","title":{"rendered":"El dec\u00e1logo de la AIE para que Europa reduzca su dependencia del gas ruso"},"content":{"rendered":"<p>\u00abLa dependencia de Europa del gas natural importado de Rusia <strong>ha vuelto a ponerse de relieve con la invasi\u00f3n rusa<\/strong> de Ucrania\u00bb, comenta la AIE en un comunicado, afirmando que el dec\u00e1logo de medidas \u00abincluye una serie de acciones complementarias que se pueden tomar en los pr\u00f3ximos meses, como recurrir m\u00e1s a otros proveedores, recurrir a otras fuentes de energ\u00eda y acelerar los esfuerzos para proporcionar a los consumidores, las empresas y la industria con los medios para utilizar alternativas limpias y eficientes al gas natural\u00bb.<\/p>\n<div class=\"read-more-links\">\n<h5>Noticia relacionada<\/h5>\n<p><a class=\"readMore\" href=\"https:\/\/www.bolsamania.com\/en-directo\/europa\/rusia-ataca-ucrania-guerra-ultima-hora.html\" rel=\"noopener noreferrer\" target=\"_blank\" data-id=\"9279579\" rel=\"nofollow\" ><\/p>\n<figure><img class=\"lazy\" title=\"Leer m&#xE1;s\" data-original=\"https:\/\/img1.s3wfg.com\/web\/img\/images_uploaded\/6\/a\/ucrania-rusia-guerra_285x185.jpg\" data-src=\"https:\/\/img1.s3wfg.com\/web\/img\/images_uploaded\/6\/a\/ucrania-rusia-guerra_285x185.jpg\" \/><\/figure>\n<p>Macron, pesimista tras hablar con Putin: \u00abLo peor est\u00e1 por llegar\u00bb <\/a><\/div>\n<p>Para ejemplificar de la dependencia de Rusia, los <strong>155.000 millones de metros c\u00fabicos de gas natural que se importaron de este pa\u00eds <\/strong>representaron el 45% del total de importaciones y el 40% del consumo. El progreso hacia las ambiciones netas cero de Europa reducir\u00e1 su uso y las importaciones de gas con el tiempo, pero la crisis actual plantea la pregunta espec\u00edfica sobre estas compras y qu\u00e9 m\u00e1s se puede hacer en el futuro inmediato para reducirlas.<\/p>\n<p>\u00abEl uso de Rusia de sus recursos de gas natural<strong> como arma econ\u00f3mica y pol\u00edtica<\/strong> muestra que Europa necesita actuar r\u00e1pidamente para estar lista para enfrentar una incertidumbre considerable sobre el suministro de gas ruso el pr\u00f3ximo invierno\u201d, ha afirmado el director ejecutivo de la AIE, <strong>Fatih Birol.<\/strong><\/p>\n<p>\u00abM\u00e1s que nunca, <strong>es esencial deshacerse de los combustibles f\u00f3siles rusos<\/strong> y de los combustibles f\u00f3siles en general. Lo que est\u00e1 en juego es tanto la necesidad de acelerar la lucha contra el cambio clim\u00e1tico como la seguridad energ\u00e9tica a corto plazo del continente europeo\u00bb, ha se\u00f1alado <strong>Barbara Pompili,<\/strong> ministra de Transici\u00f3n Ecol\u00f3gica en Francia.<\/p>\n<p>\u00ab<strong>Reducir nuestra dependencia del gas ruso es un imperativo estrat\u00e9gico para la Uni\u00f3n Europea<\/strong>\u00ab, indica Kadri Simson, comisario europeo de Energ\u00eda.<\/p>\n<h3><strong>EL DEC\u00c1LOGO<\/strong><\/h3>\n<p>Las medidas propuestas por la AIE son las siguientes:<\/p>\n<ul>\n<li><strong>No firmar ning\u00fan nuevo contrato<\/strong> de suministro de gas con Rusia, permitiendo una mayor diversificaci\u00f3n de la oferta.<\/li>\n<li><strong>Reemplazar los suministros<\/strong> de gas con fuentes alternativas.<\/li>\n<li>I<strong>ntroducir obligaciones m\u00ednimas de almacenamiento de gas<\/strong>, mejorando la resiliencia del sistema para el pr\u00f3ximo invierno.<\/li>\n<li><strong>Acelerar el despliegue de nuevos proyectos e\u00f3licos solares,<\/strong> reduciendo el uso de gas en 6.000 millones de metros c\u00fabicos en un a\u00f1o.<\/li>\n<li>Maximizar la generaci\u00f3n de energ\u00eda a partir de<strong> bioenerg\u00eda y nuclear<\/strong>, reduciendo el uso del gas en 13.000 millones de metros c\u00fabicos al a\u00f1o.<\/li>\n<li>Promulgar <strong>medidas fiscales a corto plazo<\/strong> sobre las ganancias inesperadas para proteger a los consumidores vulnerables de electricidad de los altos precios, reduciendo las facturas de energ\u00eda incluso cuando los precios del gas son altos.<\/li>\n<li>Acelerar<strong> el reemplazo de calderas de gas<\/strong> por bombas de calor, reduciendo el uso de cas en 2.000 millones de metros c\u00fabicos en un a\u00f1o.<\/li>\n<li>Acelerar <strong>las mejoras de eficiencia energ\u00e9tica en los edificios y la industria<\/strong>, con un impacto de 2.000 millones de metros c\u00fabicos de gas anuales.<\/li>\n<li>Fomentar una<strong> reducci\u00f3n temporal del termostato de 1 \u00b0C<\/strong> por parte de los consumidores, reduciendo as\u00ed el uso de gas en 10.000 millones de metros c\u00fabicos en un a\u00f1o.<\/li>\n<li>Intensificar los esfuerzos para <strong>diversificar y descarbonizar<\/strong> las fuentes de flexibilidad del sistema el\u00e9ctrico.<\/li>\n<\/ul>\n<p>En conjunto, estos pasos podr\u00edan reducir las importaciones de gas ruso de la Uni\u00f3n Europea en m\u00e1s de 50.000 millones de metros c\u00fabicos, o m\u00e1s de un tercio, dentro de un a\u00f1o, estima la AIE.<\/p>\n<p>&#013;<br \/>\nSource: Bolsamania.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLa dependencia de Europa del gas natural importado de Rusia ha vuelto a ponerse de relieve con la invasi\u00f3n rusa&#8230;<\/p>\n","protected":false},"author":1,"featured_media":51328,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[104],"tags":[99],"_links":{"self":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/51327"}],"collection":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/comments?post=51327"}],"version-history":[{"count":0,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/51327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/media\/51328"}],"wp:attachment":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/media?parent=51327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/categories?post=51327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/tags?post=51327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}