{"id":58042,"date":"2023-03-06T05:00:00","date_gmt":"2023-03-06T05:00:00","guid":{"rendered":"https:\/\/tuavaluo.com\/avaluo\/2023\/03\/06\/barclays-jefferies-jp-morgan-las-firmas-internacionales-suben-su-valoracion-de-aena\/"},"modified":"2023-03-06T05:00:00","modified_gmt":"2023-03-06T05:00:00","slug":"barclays-jefferies-jp-morgan-las-firmas-internacionales-suben-su-valoracion-de-aena","status":"publish","type":"post","link":"https:\/\/tuavaluo.com\/avaluo\/2023\/03\/06\/barclays-jefferies-jp-morgan-las-firmas-internacionales-suben-su-valoracion-de-aena\/","title":{"rendered":"Barclays, Jefferies, JP Morgan&#8230; las firmas internacionales suben su valoraci\u00f3n de Aena"},"content":{"rendered":"<p>Explica Barclays que este incremento responde a que <strong>esperan un mayor crecimiento del n\u00famero de pasajeros<\/strong> (concentrado en el ejercicio 2023) y una reducci\u00f3n interanual de la base de costes durante este a\u00f1o ya que <strong>la normalizaci\u00f3n de los costes el\u00e9ctricos diluye la inflaci\u00f3n de costes. <\/strong><\/p>\n<p>Aena es uno de los valores del Ibex que mejor lo hace en bolsa en el a\u00f1o, <strong>con alzas acumuladas cercanas al 30%<\/strong>. Este pasado 28 de febrero comunic\u00f3 que ha dejado atr\u00e1s las p\u00e9rdidas de la pandemia, con <a href=\"https:\/\/www.bolsamania.com\/noticias\/resultados-anuncios\/aena-gana-901-millones-euros-2022-pagara-dividendo-475-euros-accion--12492924.html\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"nofollow\" ><strong>un beneficio neto en 2022 de 901,5 millones de euros frente a los n\u00fameros rojos de 475,4 millones de 2021<\/strong><\/a>. Adem\u00e1s, el operador aeroportuario inform\u00f3 del pago de <strong>un dividendo de 4,75 euros por acci\u00f3n<\/strong> con cargo a los resultados de 2022.<\/p>\n<p>La compa\u00f1\u00eda <strong>ha previsto un tr\u00e1fico para el ejercicio fiscal 2023 en el rango del 94%-104%<\/strong> frente a l\u00ednea base de 2021, lo que los analistas de Barclays consideran <strong>\u00abconservador\u00bb<\/strong>.<\/p>\n<p>\u00abPensamos que es una previsi\u00f3n conservadora <strong>dado que el tr\u00e1fico de enero ya est\u00e1 un 2% por encima de la prepandemia<\/strong>, mientras que nuestro primer an\u00e1lisis de la programaci\u00f3n de verano de las compa\u00f1\u00eda a\u00e9reas muestra una capacidad total tambi\u00e9n superior a los niveles prepand\u00e9micos\u00bb, precisan estos expertos.<\/p>\n<p>Los aeropuertos de la red de Aena <a href=\"https:\/\/www.bolsamania.com\/noticias\/empresas\/aeropuertos-aena-superan-primera-vez-datos-prepandemia--12308422.html\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"nofollow\" ><strong>cerraron el mes de enero de 2023 con 16.930.100 pasajeros, superando as\u00ed en un 2,1% los datos del mismo mes de 2019<\/strong><\/a>, a\u00f1o prepandemia, y registrando un aumento del 62,7% con respecto a enero de 2022.<\/p>\n<h3>M\u00c1S MEJORAS<\/h3>\n<p>El incremento de valoraci\u00f3n de Barclays sigue a otros, como <a href=\"https:\/\/www.bolsamania.com\/noticias\/analisis-fundamental\/jefferies-mejora-precio-aena-pide-cautela-sobreexposicion-europa--12161596.html\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"nofollow\" ><strong>el que anunci\u00f3 Jefferies a principios de este mes<\/strong><\/a>. As\u00ed, <strong>subi\u00f3 el precio objetivo hasta 130 desde 120 euros, con un consejo de &#8216;mantener&#8217;.<\/strong> El banco de inversi\u00f3n estadounidense se refiere tambi\u00e9n al incremento del n\u00famero de pasajeros. As\u00ed, ha elevado un 4% sus previsiones para 2023, al tiempo que reconoce que la temporada invernal ha sido \u00abexcepcionalmente fuerte en relaci\u00f3n con las expectativas\u00bb.<\/p>\n<p>Desde Jefferies esperan un \u201cmodesto\u201d aumento de los gastos de explotaci\u00f3n, y tambi\u00e9n <strong>consideran que los menores costes energ\u00e9ticos compensar\u00e1n \u201cparcialmente\u201d la inflaci\u00f3n de los costes subyacentes<\/strong>. \u201cEsto supone 2.200 millones de euros de EBITDA en 2023 y 2.700 millones de euros en 2024\u201d, a\u00f1aden.<\/p>\n<p>Asimismo, comentan que la cautela viene ante posibles sorpresas negativas en Europa. \u201cNuestra cautela se debe a la posici\u00f3n sobreponderada de Aena en Europa, que es donde <strong>vemos el mayor riesgo de ca\u00edda de la demanda<\/strong> (alrededor del 90% de los beneficios frente al 75% de ADP y el 60% de Fraport), y al <strong>marco regulador de Aena, que ofrece poca flexibilidad de precios<\/strong> hasta 2026 a pesar de las presiones inflacionistas\u201d.<\/p>\n<p>JP Morgan tambi\u00e9n <a href=\"https:\/\/www.bolsamania.com\/noticias\/empresas\/jp-morgan-eleva-valoracion-aena-148-euros-espera-subidas-corto-plazo--11612004.html\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"nofollow\" ><strong>elev\u00f3 el precio de Aena a finales de enero hasta 153 euros desde 148 euros, con un consejo de &#8216;sobreponderar&#8217;<\/strong><\/a>. Seg\u00fan la firma neoyorquina, pese a la subida de las acciones en lo que llevamos de 2023,<strong> la valoraci\u00f3n \u201csigue siendo favorable\u201d<\/strong>, ya que la ratio valor empresarial\/EBITDA (EV\/EBITDA, en ingl\u00e9s) est\u00e1 \u201campliamente en l\u00ednea con la media hist\u00f3rica antes del Covid\u201d.<\/p>\n<p>\u201cNuestras estimaciones de EBITDA para 2023 se sit\u00faan <strong>un 3% por encima del consenso<\/strong>, sobre unas hip\u00f3tesis que consideramos poco exigentes, incluso teniendo en cuenta el contexto de recesi\u00f3n\u201d, explican estos expertos.<\/p>\n<p>En particular, JP Morgan <strong>ve catalizadores positivos en las expectativas de tr\u00e1fico y en los costes de la energ\u00eda<\/strong>, como el resto de expertos, ya que considera \u201cprobable\u201d que Aena se beneficie \u201cplenamente\u201d del reciente descenso de los costes de la electricidad en 2023 tras los fuertes vientos en contra registrados en 2022.<\/p>\n<p>Cabe destacar, por \u00faltimo, que a finales de enero, <a href=\"https:\/\/www.bolsamania.com\/fundsnews\/noticias\/gestoras\/bestinver-redobla-apuesta-sector-financiero-inditex-entra-aena-heineken--12099242.html\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"nofollow\" ><strong>Bestinver anunciaba que hab\u00eda incorporado a Aena a sus carteras<\/strong><\/a> en los meses previos, una compa\u00f1\u00eda \u00abmuy deprimida que lo ha hecho muy bien\u00bb, afirmaba.<\/p>\n<p>&#013;<br \/>\nSource: Bolsamania.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Explica Barclays que este incremento responde a que esperan un mayor crecimiento del n\u00famero de pasajeros (concentrado en el ejercicio&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[104],"tags":[99],"_links":{"self":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/58042"}],"collection":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/comments?post=58042"}],"version-history":[{"count":0,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/58042\/revisions"}],"wp:attachment":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/media?parent=58042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/categories?post=58042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/tags?post=58042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}