{"id":60169,"date":"2023-04-20T12:10:19","date_gmt":"2023-04-20T12:10:19","guid":{"rendered":"https:\/\/tuavaluo.com\/avaluo\/2023\/04\/20\/el-bce-cumplio-subiendo-los-tipos-en-marzo-para-dar-confianza-y-evitar-incertidumbre\/"},"modified":"2023-04-20T12:10:19","modified_gmt":"2023-04-20T12:10:19","slug":"el-bce-cumplio-subiendo-los-tipos-en-marzo-para-dar-confianza-y-evitar-incertidumbre","status":"publish","type":"post","link":"https:\/\/tuavaluo.com\/avaluo\/2023\/04\/20\/el-bce-cumplio-subiendo-los-tipos-en-marzo-para-dar-confianza-y-evitar-incertidumbre\/","title":{"rendered":"El BCE cumpli\u00f3 subiendo los tipos en marzo para dar confianza y evitar incertidumbre"},"content":{"rendered":"<div class=\"read-more-links\">\n<h5>Noticia relacionada<\/h5>\n<p><a class=\"readMore\" href=\"https:\/\/www.bolsamania.com\/noticias\/mercados\/bce-sube-tipos-05-esta-preparado-responder-si-es-necesario--12699908.html\" rel=\"noopener noreferrer\" target=\"_blank\" data-id=\"12699908\" rel=\"nofollow\" ><\/p>\n<figure><img class=\"lazy\" title=\"Leer m&#xE1;s\" data-original=\"https:\/\/img3.s3wfg.com\/web\/img\/images_uploaded\/b\/9\/c-est-aux-gouvernements-pas-a-la-bce-de-reduire-les-tensions-sur-l-energie-lagarde_rsz.png\" data-src=\"https:\/\/img3.s3wfg.com\/web\/img\/images_uploaded\/b\/9\/c-est-aux-gouvernements-pas-a-la-bce-de-reduire-les-tensions-sur-l-energie-lagarde_rsz.png\" \/><\/figure>\n<p>El BCE sube tipos un 0,5% y \u00abest\u00e1 preparado para responder si es necesario\u00bb <\/a><\/div>\n<p>\u00abUna amplia mayor\u00eda estuvo de acuerdo con la propuesta de <a href=\"https:\/\/www.bolsamania.com\/noticias\/mercados\/bce-sube-tipos-05-esta-preparado-responder-si-es-necesario--12699908.html\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"nofollow\" >subir los tipos de inter\u00e9s oficiales del BCE en 50 puntos b\u00e1sicos<\/a>, en l\u00ednea con la intenci\u00f3n comunicada por el Consejo de Gobierno en su \u00faltima reuni\u00f3n de pol\u00edtica monetaria\u00bb y \u00abse consider\u00f3 importante <strong>seguir la trayectoria anunciada<\/strong> de tipos de inter\u00e9s para <strong>infundir confianza y evitar crear m\u00e1s incertidumbre<\/strong> en los mercados financieros\u00bb, detallan las actas.<\/p>\n<p>No obstante, aunque esta decisi\u00f3n fue apoyada por una amplia mayor\u00eda, hubo algunos miembros que hubieran preferido <strong>no aumentar los tipos hasta que las tensiones en los mercados financieros hubieran disminuido<\/strong> \u00aby realizar una reevaluaci\u00f3n integral de la postura en la pr\u00f3xima reuni\u00f3n de pol\u00edtica monetaria del Consejo de Gobierno, en mayo\u00bb<\/p>\n<p>En cuanto a la inflaci\u00f3n, se destac\u00f3 que estaba muy por encima del objetivo del Consejo de Gobierno y que la din\u00e1mica segu\u00eda siendo \u00abdemasiado fuerte, lo que<strong> justificaba un incremento de 50 puntos b\u00e1sicos<\/strong> en los tipos de inter\u00e9s oficiales\u00bb.<\/p>\n<p>Adem\u00e1s, los miembros enfatizaron que segu\u00eda siendo demasiado alta y se proyectaba que permanecer\u00eda as\u00ed durante m\u00e1s tiempo. En este contexto, <strong>\u00aba la pol\u00edtica monetaria todav\u00eda le queda un trecho por recorrer para reducir la inflaci\u00f3n\u00bb<\/strong>, con lo que, \u00aben vista del riesgo de una din\u00e1mica inflacionaria persistente, la pol\u00edtica monetaria del BCE tambi\u00e9n ten\u00eda que ser persistente\u00bb, se\u00f1ala el documento.<\/p>\n<p>As\u00ed, si se confirman las perspectivas de inflaci\u00f3n incluidas en las proyecciones de los expertos del BCE de marzo, \u00abel Consejo de Gobierno tendr\u00eda m\u00e1s terreno que recorrer para ajustar la orientaci\u00f3n de la pol\u00edtica monetaria a fin de garantizar que la inflaci\u00f3n regrese a tiempo al objetivo\u00bb, a\u00f1aden.<\/p>\n<p>En general, los miembros acordaron que el Consejo de Gobierno deber\u00eda <strong>abstenerse de comunicar expectativas incondicionales para la evoluci\u00f3n futura de los tipos de inter\u00e9s<\/strong>. Sin embargo, se expres\u00f3 la preocupaci\u00f3n de que la ausencia de dicha orientaci\u00f3n podr\u00eda interpretarse como una indicaci\u00f3n de que el ciclo de aumentos estaba llegando a su fin. \u00abPor esta raz\u00f3n, se sugiri\u00f3 transmitir el mensaje de que, de no haber ocurrido la reciente turbulencia en los mercados, el Consejo de Gobierno habr\u00eda expresado la expectativa de que aumentar\u00eda a\u00fan m\u00e1s los tipos, dado el escenario base\u00bb.<\/p>\n<p>&#013;<br \/>\nSource: Bolsamania.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noticia relacionada El BCE sube tipos un 0,5% y \u00abest\u00e1 preparado para responder si es necesario\u00bb \u00abUna amplia mayor\u00eda estuvo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":60170,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[104],"tags":[99],"_links":{"self":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/60169"}],"collection":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/comments?post=60169"}],"version-history":[{"count":0,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/60169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/media\/60170"}],"wp:attachment":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/media?parent=60169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/categories?post=60169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/tags?post=60169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}