{"id":69349,"date":"2024-01-08T07:25:08","date_gmt":"2024-01-08T07:25:08","guid":{"rendered":"https:\/\/tuavaluo.com\/avaluo\/2024\/01\/08\/soltec-cierra-el-traspaso-a-aquila-del-49-de-un-proyecto-de-52-mw-en-italia\/"},"modified":"2024-01-08T07:25:08","modified_gmt":"2024-01-08T07:25:08","slug":"soltec-cierra-el-traspaso-a-aquila-del-49-de-un-proyecto-de-52-mw-en-italia","status":"publish","type":"post","link":"https:\/\/tuavaluo.com\/avaluo\/2024\/01\/08\/soltec-cierra-el-traspaso-a-aquila-del-49-de-un-proyecto-de-52-mw-en-italia\/","title":{"rendered":"Soltec cierra el traspaso a Aquila del 49% de un proyecto de 52 MW en Italia"},"content":{"rendered":"<p>El acuerdo garantiza que <strong>los proyectos utilizar\u00e1n seguidores solares y servicios de construcci\u00f3n de Soltec<\/strong>.<\/p>\n<p>La operaci\u00f3n generar\u00e1 <strong>una entrada de caja en el ejercicio 2023 de 3,8 millones de euros<\/strong>.<\/p>\n<p>&#013;<br \/>\nSource: Bolsamania.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El acuerdo garantiza que los proyectos utilizar\u00e1n seguidores solares y servicios de construcci\u00f3n de Soltec. La operaci\u00f3n generar\u00e1 una entrada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[104],"tags":[99],"_links":{"self":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/69349"}],"collection":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/comments?post=69349"}],"version-history":[{"count":0,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/69349\/revisions"}],"wp:attachment":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/media?parent=69349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/categories?post=69349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/tags?post=69349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}