{"id":73382,"date":"2024-04-04T08:59:41","date_gmt":"2024-04-04T08:59:41","guid":{"rendered":"https:\/\/tuavaluo.com\/avaluo\/2024\/04\/04\/oryzon-recibe-el-sello-de-pyme-innovadora-del-ministerio-de-ciencia-e-innovacion\/"},"modified":"2024-04-04T08:59:41","modified_gmt":"2024-04-04T08:59:41","slug":"oryzon-recibe-el-sello-de-pyme-innovadora-del-ministerio-de-ciencia-e-innovacion","status":"publish","type":"post","link":"https:\/\/tuavaluo.com\/avaluo\/2024\/04\/04\/oryzon-recibe-el-sello-de-pyme-innovadora-del-ministerio-de-ciencia-e-innovacion\/","title":{"rendered":"Oryzon recibe el sello de pyme innovadora del Ministerio de Ciencia e Innovaci\u00f3n"},"content":{"rendered":"<p>Mediante la concesi\u00f3n de esta distinci\u00f3n, cuyo objetivo es premiar y poner en valor <strong>las actividades de las pymes en materia de I+D+i<\/strong>,<strong> <\/strong>\u00abel Ministerio reconoce de forma oficial el car\u00e1cter innovador y pionero de los estudios y avances cl\u00ednicos de Oryzon en el<strong> campo de la epigen\u00e9tica<\/strong>. Esta es la cuarta vez consecutiva que Oryzon recibe el sello de pyme innovadora\u00bb, ha se\u00f1alado la compa\u00f1\u00eda en un comunicado.<\/p>\n<p>La compa\u00f1\u00eda se\u00f1ala ser pionera en el desarrollo de inhibidores de LSD1 en el campo de <strong>enfermedades psiqui\u00e1tricas y neurodegenerativas<\/strong>. \u00abLa compa\u00f1\u00eda ha mostrado un buen perfil de seguridad en ensayos cl\u00ednicos, con<strong> m\u00e1s de 400 sujetos<\/strong> tratados, y ha mostrado ser eficaz en la reducci\u00f3n de la agitaci\u00f3n y agresividad en estudios cl\u00ednicos en pacientes con<strong> trastorno l\u00edmite de la personalidad<\/strong> (TLP), <strong>trastorno por d\u00e9ficit de atenci\u00f3n e hiperactividad<\/strong> (TDAH),<strong> trastorno del espectro autista<\/strong> (TEA) y<strong> enfermedad de Alzheimer<\/strong>\u00ab.<\/p>\n<p>Asimismo, actualmente Oryzon tiene en marcha un ensayo cl\u00ednico (estudio FRIDA) de iadademstat en combinaci\u00f3n con gilteritinib en pacientes con<strong> leucemia mieloide aguda (LMA) recidivante\/refractaria<\/strong>.<\/p>\n<p>&#013;<br \/>\nSource: Bolsamania.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mediante la concesi\u00f3n de esta distinci\u00f3n, cuyo objetivo es premiar y poner en valor las actividades de las pymes en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[104],"tags":[99],"_links":{"self":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/73382"}],"collection":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/comments?post=73382"}],"version-history":[{"count":0,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/73382\/revisions"}],"wp:attachment":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/media?parent=73382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/categories?post=73382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/tags?post=73382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}