{"id":83060,"date":"2024-11-25T15:54:33","date_gmt":"2024-11-25T15:54:33","guid":{"rendered":"https:\/\/tuavaluo.com\/avaluo\/2024\/11\/25\/las-gestoras-ven-preocupaciones-potenciales-en-la-opa-de-unicredit-sobre-banco-bpm\/"},"modified":"2024-11-25T15:54:33","modified_gmt":"2024-11-25T15:54:33","slug":"las-gestoras-ven-preocupaciones-potenciales-en-la-opa-de-unicredit-sobre-banco-bpm","status":"publish","type":"post","link":"https:\/\/tuavaluo.com\/avaluo\/2024\/11\/25\/las-gestoras-ven-preocupaciones-potenciales-en-la-opa-de-unicredit-sobre-banco-bpm\/","title":{"rendered":"Las gestoras ven &quot;preocupaciones potenciales&quot; en la OPA de UniCredit sobre Banco BPM"},"content":{"rendered":"<p>\u00abEsta adquisici\u00f3n tendr\u00e1 un impacto limitado en los colchones de capital de UniCredit debido a la estructura de todas las acciones, pero existen preocupaciones potenciales sobre el riesgo de concentraci\u00f3n y los diferenciales. <strong>Yo esperar\u00eda que la adquisici\u00f3n tuviera un impacto positivo en los diferenciales de cr\u00e9dito de Banco BPM<\/strong>, aunque la prima de emisi\u00f3n es modesta\u00bb, asegura<strong> Flippo Alloati<\/strong>, director de finanzas para cr\u00e9dito en Federated Hermes.<\/p>\n<p>Adem\u00e1s, subraya que \u00ab<strong>este movimiento de la direcci\u00f3n de UniCredit subraya su agilidad estrat\u00e9gica y su compromiso de reforzar su posici\u00f3n de mercado en Italia<\/strong>\u00ab. Se espera que la transacci\u00f3n se complete en junio de 2025, y UniCredit ha asegurado que su pol\u00edtica de dividendos para 2024 se mantendr\u00e1 sin cambios.<\/p>\n<p>\u00abPor otro lado<strong>, Commerzbank podr\u00eda ver implicaciones negativas<\/strong>, con una probabilidad m\u00e1s reducida ahora o un plazo m\u00e1s largo. El anuncio de hoy tambi\u00e9n pone en peligro la combinaci\u00f3n de Monte dei Paschi y Banco BPM, ya que Banco BPM y Anima Holding ya poseen una participaci\u00f3n del 9% en Monte dei Paschi\u00bb, a\u00f1ade.<\/p>\n<p>Por su parte, Marco Troiano, analista de instituciones financieras para Scope Ratings, asegura que la oferta confirma su opini\u00f3n de que \u00ab<strong>hay m\u00e1s potencial para la consolidaci\u00f3n nacional en Italia, Espa\u00f1a, Alemania y el Reino Unido que para la actividad transfronteriza<\/strong>\u00ab.<\/p>\n<p>\u00abLa oferta de UniCredit por BPM se produce tras la oferta de DNB por Carnegie (una operaci\u00f3n regional n\u00f3rdica), la oferta de BBVA por Sabadell y una serie de fusiones y adquisiciones bancarias nacionales en el Reino Unido. Aunque la reciente toma de participaci\u00f3n de UniCredit en Commerzbank es oficialmente una operaci\u00f3n internacional, no la consideramos una operaci\u00f3n internacional cl\u00e1sica, pues<strong> UniCredit ya cuenta con un importante negocio en Alemania a trav\u00e9s de HVB<\/strong>\u00ab, detalla.<\/p>\n<p>Este analista considera que \u00ab<strong>las fusiones y adquisiciones nacionales tienen un mayor potencial de creaci\u00f3n de valor<\/strong>, debido a las sinergias de costes en la distribuci\u00f3n f\u00edsica y en el solapamiento de funciones centralizadas\u00bb, mientras que \u00ablos argumentos a favor de las megafusiones transfronterizas siguen siendo d\u00e9biles\u00bb.<\/p>\n<p>\u00abLas conjeturas sobre fusiones y adquisiciones bancarias han aumentado a la par que<strong> la actividad de los gobiernos europeos para salir de las participaciones en bancos que adquirieron en la \u00e9poca de la crisis financiera mundial.<\/strong> M\u00e1s all\u00e1 del hecho de que los bancos europeos est\u00e1n en mejor forma desde el punto de vista del capital, la salida de los gobiernos ha contribuido a reforzar la confianza en el sector, que ahora se considera capaz de operar de forma independiente\u00bb, concluye.<\/p>\n<p>&#013;<br \/>\nSource: Bolsamania.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abEsta adquisici\u00f3n tendr\u00e1 un impacto limitado en los colchones de capital de UniCredit debido a la estructura de todas las&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[104],"tags":[99],"_links":{"self":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/83060"}],"collection":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/comments?post=83060"}],"version-history":[{"count":0,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/posts\/83060\/revisions"}],"wp:attachment":[{"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/media?parent=83060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/categories?post=83060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuavaluo.com\/avaluo\/wp-json\/wp\/v2\/tags?post=83060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}